{"id":70388,"date":"2023-04-05T15:26:00","date_gmt":"2023-04-05T13:26:00","guid":{"rendered":"http:\/\/valvex.com\/product\/bateria-wannowa-bez-akcesoriow-2\/"},"modified":"2024-03-05T17:01:06","modified_gmt":"2024-03-05T16:01:06","slug":"ars-bateria-wannowa-bez-akcesoriow-2","status":"publish","type":"product","link":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/","title":{"rendered":"Badewannen-Wand-Mischbatterie mit Garnitur"},"content":{"rendered":"","protected":false},"featured_media":79571,"template":"","ikony_produktow":[2111,2112,2113],"product_category":[1931,1946],"product_series":[2123],"color":[1762],"class_list":["post-70388","product","type-product","status-publish","has-post-thumbnail","hentry","ikony_produktow-25jahregarantie","ikony_produktow-48-stunden-serviceinpolen","ikony_produktow-keramikkartuschede","product_category-badewanne","product_category-badewannenarmaturen","product_series-ars-de","color-black"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Badewannen-Wand-Mischbatterie mit Garnitur - Valvex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Badewannen-Wand-Mischbatterie mit Garnitur - Valvex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Valvex\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T16:01:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valvex.com\/wp-content\/uploads\/2023\/04\/VALVEX_2420420_ARS-Black.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/\",\"url\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/\",\"name\":\"Badewannen-Wand-Mischbatterie mit Garnitur - Valvex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/VALVEX_2420420_ARS-Black-1.png\",\"datePublished\":\"2023-04-05T13:26:00+00:00\",\"dateModified\":\"2024-03-05T16:01:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/VALVEX_2420420_ARS-Black-1.png\",\"contentUrl\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/VALVEX_2420420_ARS-Black-1.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/ars-bateria-wannowa-bez-akcesoriow-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Badezimmer\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/oferta\\\/badezimmer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Badewanne\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/oferta\\\/badezimmer\\\/badewanne\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Badewannenarmaturen\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/oferta\\\/badezimmer\\\/badewanne\\\/badewannenarmaturen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Badewannen-Wand-Mischbatterie mit Garnitur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/valvex.com\\\/de\\\/\",\"name\":\"Valvex\",\"description\":\"Hersteller von Sanit\u00e4ranlagen und Armaturen\\n\\n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valvex.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Badewannen-Wand-Mischbatterie mit Garnitur - Valvex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/","og_locale":"de_DE","og_type":"article","og_title":"Badewannen-Wand-Mischbatterie mit Garnitur - Valvex","og_url":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/","og_site_name":"Valvex","article_modified_time":"2024-03-05T16:01:06+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/valvex.com\/wp-content\/uploads\/2023\/04\/VALVEX_2420420_ARS-Black.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/","url":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/","name":"Badewannen-Wand-Mischbatterie mit Garnitur - Valvex","isPartOf":{"@id":"https:\/\/valvex.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/#primaryimage"},"image":{"@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/#primaryimage"},"thumbnailUrl":"https:\/\/valvex.com\/wp-content\/uploads\/2023\/04\/VALVEX_2420420_ARS-Black-1.png","datePublished":"2023-04-05T13:26:00+00:00","dateModified":"2024-03-05T16:01:06+00:00","breadcrumb":{"@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/#primaryimage","url":"https:\/\/valvex.com\/wp-content\/uploads\/2023\/04\/VALVEX_2420420_ARS-Black-1.png","contentUrl":"https:\/\/valvex.com\/wp-content\/uploads\/2023\/04\/VALVEX_2420420_ARS-Black-1.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/valvex.com\/de\/produkt\/ars-bateria-wannowa-bez-akcesoriow-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/valvex.com\/de\/"},{"@type":"ListItem","position":2,"name":"Badezimmer","item":"https:\/\/valvex.com\/de\/oferta\/badezimmer\/"},{"@type":"ListItem","position":3,"name":"Badewanne","item":"https:\/\/valvex.com\/de\/oferta\/badezimmer\/badewanne\/"},{"@type":"ListItem","position":4,"name":"Badewannenarmaturen","item":"https:\/\/valvex.com\/de\/oferta\/badezimmer\/badewanne\/badewannenarmaturen\/"},{"@type":"ListItem","position":5,"name":"Badewannen-Wand-Mischbatterie mit Garnitur"}]},{"@type":"WebSite","@id":"https:\/\/valvex.com\/de\/#website","url":"https:\/\/valvex.com\/de\/","name":"Valvex","description":"Hersteller von Sanit\u00e4ranlagen und Armaturen\n\n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valvex.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product\/70388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/media\/79571"}],"wp:attachment":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/media?parent=70388"}],"wp:term":[{"taxonomy":"ikony_produktow","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/ikony_produktow?post=70388"},{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product_category?post=70388"},{"taxonomy":"product_series","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product_series?post=70388"},{"taxonomy":"color","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/color?post=70388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}