{"id":50860,"date":"2019-07-08T23:10:16","date_gmt":"2019-07-08T21:10:16","guid":{"rendered":"http:\/\/valvex.com\/product\/combi-verschlussscheibe-fuer-den-kesselverteiler\/"},"modified":"2024-05-21T10:13:38","modified_gmt":"2024-05-21T08:13:38","slug":"combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860","status":"publish","type":"product","link":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/","title":{"rendered":"Verschlussscheibe f\u00fcr den Kesselverteiler"},"content":{"rendered":"","protected":false},"featured_media":50858,"template":"","ikony_produktow":[],"product_category":[234,329,389],"product_series":[1244],"color":[],"class_list":["post-50860","product","type-product","status-publish","has-post-thumbnail","hentry","product_category-anlagenbereich","product_category-heizanlagensysteme","product_category-verteilerteile","product_series-combi-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/\" \/>\n<meta property=\"og:site_name\" content=\"Valvex\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T08:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valvex.com\/wp-content\/uploads\/2022\/03\/6096770.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/\",\"url\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/\",\"name\":\"Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/6096770.jpg\",\"datePublished\":\"2019-07-08T21:10:16+00:00\",\"dateModified\":\"2024-05-21T08:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/6096770.jpg\",\"contentUrl\":\"https:\\\/\\\/valvex.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/6096770.jpg\",\"width\":650,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/produkt\\\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anlagenbereich\",\"item\":\"https:\\\/\\\/valvex.com\\\/de\\\/oferta\\\/anlagenbereich\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verschlussscheibe f\u00fcr den Kesselverteiler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valvex.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/valvex.com\\\/de\\\/\",\"name\":\"Valvex\",\"description\":\"Hersteller von Sanit\u00e4ranlagen und Armaturen\\n\\n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valvex.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/","og_locale":"de_DE","og_type":"article","og_title":"Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex","og_url":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/","og_site_name":"Valvex","article_modified_time":"2024-05-21T08:13:38+00:00","og_image":[{"width":650,"height":415,"url":"https:\/\/valvex.com\/wp-content\/uploads\/2022\/03\/6096770.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/","url":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/","name":"Verschlussscheibe f\u00fcr den Kesselverteiler - Valvex","isPartOf":{"@id":"https:\/\/valvex.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/#primaryimage"},"image":{"@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/#primaryimage"},"thumbnailUrl":"https:\/\/valvex.com\/wp-content\/uploads\/2022\/03\/6096770.jpg","datePublished":"2019-07-08T21:10:16+00:00","dateModified":"2024-05-21T08:13:38+00:00","breadcrumb":{"@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/#primaryimage","url":"https:\/\/valvex.com\/wp-content\/uploads\/2022\/03\/6096770.jpg","contentUrl":"https:\/\/valvex.com\/wp-content\/uploads\/2022\/03\/6096770.jpg","width":650,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/valvex.com\/de\/produkt\/combi-verschlussscheibe-f%c3%bcr-den-kesselverteiler-50860\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/valvex.com\/de\/"},{"@type":"ListItem","position":2,"name":"Anlagenbereich","item":"https:\/\/valvex.com\/de\/oferta\/anlagenbereich\/"},{"@type":"ListItem","position":3,"name":"Verschlussscheibe f\u00fcr den Kesselverteiler"}]},{"@type":"WebSite","@id":"https:\/\/valvex.com\/de\/#website","url":"https:\/\/valvex.com\/de\/","name":"Valvex","description":"Hersteller von Sanit\u00e4ranlagen und Armaturen\n\n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valvex.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product\/50860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/media\/50858"}],"wp:attachment":[{"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/media?parent=50860"}],"wp:term":[{"taxonomy":"ikony_produktow","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/ikony_produktow?post=50860"},{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product_category?post=50860"},{"taxonomy":"product_series","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/product_series?post=50860"},{"taxonomy":"color","embeddable":true,"href":"https:\/\/valvex.com\/de\/wp-json\/wp\/v2\/color?post=50860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}